{"id":1878,"date":"2023-01-20T15:27:22","date_gmt":"2023-01-20T15:27:22","guid":{"rendered":"https:\/\/atse-co.com\/en\/?page_id=1878"},"modified":"2024-08-18T14:35:29","modified_gmt":"2024-08-18T14:35:29","slug":"current","status":"publish","type":"page","link":"https:\/\/atse-co.com\/en\/current\/","title":{"rendered":"Current Projects"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1878\" class=\"elementor elementor-1878\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a780761 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a780761\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1e0099\" data-id=\"e1e0099\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa0b4f7 elementor-widget elementor-widget-cz_accordion\" data-id=\"fa0b4f7\" data-element_type=\"widget\" data-widget_type=\"cz_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div data-arrows='{\"open\":\"fa czico-200-down-arrow\",\"close\":\"fa czico-199-up-arrow\"}' class=\"cz_acc clr cz_acc_first_open\"><div><div class=\"elementor-repeater-item-d54ae52\"><span class=\"cz_acc_child\"><div>Current<\/div><\/span><div class=\"cz_acc_child_content clr\"><div class=\"mb10 last0 clr\"><div class=\"clr\"><ul><li>1<\/li><li>2<\/li><li>3<\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-599be72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"599be72\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06c448a\" data-id=\"06c448a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4026fa3 elementor-invisible elementor-widget elementor-widget-cz_gallery\" data-id=\"4026fa3\" data-element_type=\"widget\" data-widget_type=\"cz_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"cz_grid_p\"><div class=\"cz_grid cz_grid_1 clr cz_metro_1 cz_grid_c4 cz_grid_1_no_title cz_grid_1_mid tac cz_grid_two_columns_on_mobile\" data-animation=\"cz_grid_anim_fade_in\"><div class=\"cz_grid_item cz_grid_first\"><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c956a2b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c956a2b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d61c19f\" data-id=\"d61c19f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7267db elementor-invisible elementor-widget elementor-widget-cz_gallery\" data-id=\"c7267db\" data-element_type=\"widget\" data-widget_type=\"cz_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"cz_grid_p\"><div class=\"cz_grid cz_grid_1 clr cz_metro_1 cz_grid_c4 cz_grid_1_no_title cz_grid_1_mid tac cz_grid_two_columns_on_mobile\" data-animation=\"cz_grid_anim_fade_in\"><div class=\"cz_grid_item cz_grid_first\"><\/div><div class=\"cz_grid_item \"><div><a class=\"cz_grid_link \" aria-lable=\"Image: 20211028_101314\" href=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/20211028_101314-scaled.jpg\" data-xtra-lightbox><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20width=&#39;600&#39;%20height=&#39;600&#39;%20viewBox%3D&#39;0%200%20600%20600&#39;%2F%3E\" data-czlz data-src=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/20211028_101314-600x600.jpg\" class=\"attachment-codevz_600_600 size-codevz_600_600 wp-image-1934\" alt=\"\" data-srcset=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/20211028_101314-600x600.jpg 600w, https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/20211028_101314-150x150.jpg 150w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"cz_grid_details\"><\/div><\/a><\/div><\/div><div class=\"cz_grid_item \"><div><a class=\"cz_grid_link \" aria-lable=\"Image: IMG_20221203_104230_395\" href=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_395.jpg\" data-xtra-lightbox><img decoding=\"async\" width=\"600\" height=\"600\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20width=&#39;600&#39;%20height=&#39;600&#39;%20viewBox%3D&#39;0%200%20600%20600&#39;%2F%3E\" data-czlz data-src=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_395-600x600.jpg\" class=\"attachment-codevz_600_600 size-codevz_600_600 wp-image-1936\" alt=\"\" data-srcset=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_395-600x600.jpg 600w, https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_395-150x150.jpg 150w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"cz_grid_details\"><\/div><\/a><\/div><\/div><div class=\"cz_grid_item \"><div><a class=\"cz_grid_link \" aria-lable=\"Image: IMG_20221203_104230_452\" href=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_452.jpg\" data-xtra-lightbox><img decoding=\"async\" width=\"600\" height=\"600\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20width=&#39;600&#39;%20height=&#39;600&#39;%20viewBox%3D&#39;0%200%20600%20600&#39;%2F%3E\" data-czlz data-src=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_452-600x600.jpg\" class=\"attachment-codevz_600_600 size-codevz_600_600 wp-image-1937\" alt=\"\" data-srcset=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_452-600x600.jpg 600w, https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_452-150x150.jpg 150w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"cz_grid_details\"><\/div><\/a><\/div><\/div><div class=\"cz_grid_item \"><div><a class=\"cz_grid_link \" aria-lable=\"Image: IMG_20221203_104230_552\" href=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_552.jpg\" data-xtra-lightbox><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20width=&#39;600&#39;%20height=&#39;600&#39;%20viewBox%3D&#39;0%200%20600%20600&#39;%2F%3E\" data-czlz data-src=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_552-600x600.jpg\" class=\"attachment-codevz_600_600 size-codevz_600_600 wp-image-1941\" alt=\"\" data-srcset=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_552-600x600.jpg 600w, https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_552-150x150.jpg 150w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"cz_grid_details\"><\/div><\/a><\/div><\/div><div class=\"cz_grid_item \"><div><a class=\"cz_grid_link \" aria-lable=\"Image: IMG_20221203_104230_817\" href=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_817.jpg\" data-xtra-lightbox><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20width=&#39;600&#39;%20height=&#39;600&#39;%20viewBox%3D&#39;0%200%20600%20600&#39;%2F%3E\" data-czlz data-src=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_817-600x600.jpg\" class=\"attachment-codevz_600_600 size-codevz_600_600 wp-image-1942\" alt=\"\" data-srcset=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_817-600x600.jpg 600w, https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_817-150x150.jpg 150w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"cz_grid_details\"><\/div><\/a><\/div><\/div><div class=\"cz_grid_item \"><div><a class=\"cz_grid_link \" aria-lable=\"Image: IMG_20221203_104230_911\" href=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_911.jpg\" data-xtra-lightbox><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20width=&#39;600&#39;%20height=&#39;600&#39;%20viewBox%3D&#39;0%200%20600%20600&#39;%2F%3E\" data-czlz data-src=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_911-600x600.jpg\" class=\"attachment-codevz_600_600 size-codevz_600_600 wp-image-1943\" alt=\"\" data-srcset=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_911-600x600.jpg 600w, https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104230_911-150x150.jpg 150w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"cz_grid_details\"><\/div><\/a><\/div><\/div><div class=\"cz_grid_item \"><div><a class=\"cz_grid_link \" aria-lable=\"Image: IMG_20221203_104239_660\" href=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104239_660.jpg\" data-xtra-lightbox><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20width=&#39;600&#39;%20height=&#39;600&#39;%20viewBox%3D&#39;0%200%20600%20600&#39;%2F%3E\" data-czlz data-src=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104239_660-600x600.jpg\" class=\"attachment-codevz_600_600 size-codevz_600_600 wp-image-1944\" alt=\"\" data-srcset=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104239_660-600x600.jpg 600w, https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/IMG_20221203_104239_660-150x150.jpg 150w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" \/><div class=\"cz_grid_details\"><\/div><\/a><\/div><\/div><div class=\"cz_grid_item \"><div><a class=\"cz_grid_link \" aria-lable=\"Image: OLYMPUS DIGITAL CAMERA\" href=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/Recovered_JPEG-Digital-Camera_2874.jpg\" data-xtra-lightbox><img loading=\"lazy\" decoding=\"async\" width=\"466\" height=\"480\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20width=&#39;466&#39;%20height=&#39;480&#39;%20viewBox%3D&#39;0%200%20466%20480&#39;%2F%3E\" data-czlz data-src=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/Recovered_JPEG-Digital-Camera_2874.jpg\" class=\"attachment-codevz_600_600 size-codevz_600_600 wp-image-1945\" alt=\"\" data-srcset=\"https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/Recovered_JPEG-Digital-Camera_2874.jpg 466w, https:\/\/atse-co.com\/en\/wp-content\/uploads\/2023\/01\/Recovered_JPEG-Digital-Camera_2874-291x300.jpg 291w\" data-sizes=\"(max-width: 466px) 100vw, 466px\" \/><div class=\"cz_grid_details\"><\/div><\/a><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Current 1 2 3 &#8230; <\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1878","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/atse-co.com\/en\/wp-json\/wp\/v2\/pages\/1878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atse-co.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/atse-co.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/atse-co.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/atse-co.com\/en\/wp-json\/wp\/v2\/comments?post=1878"}],"version-history":[{"count":13,"href":"https:\/\/atse-co.com\/en\/wp-json\/wp\/v2\/pages\/1878\/revisions"}],"predecessor-version":[{"id":2261,"href":"https:\/\/atse-co.com\/en\/wp-json\/wp\/v2\/pages\/1878\/revisions\/2261"}],"wp:attachment":[{"href":"https:\/\/atse-co.com\/en\/wp-json\/wp\/v2\/media?parent=1878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}